{"id":6228,"date":"2022-02-07T15:45:42","date_gmt":"2022-02-07T15:45:42","guid":{"rendered":"https:\/\/neuronup.com\/fr\/?p=6228"},"modified":"2025-09-23T09:11:24","modified_gmt":"2025-09-23T07:11:24","slug":"reeducation-de-lattention-divisee","status":"publish","type":"post","link":"https:\/\/neuronup.com\/fr\/activites-de-neuro-reeducation\/activites-pour-les-fonctions-cognitives\/activites-dattention\/reeducation-de-lattention-divisee\/","title":{"rendered":"R\u00e9\u00e9ducation de l&#8217;attention divis\u00e9e"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"qu-est-ce-que-l-attention-divisee\">Qu&rsquo;est-ce que l&rsquo;attention divis\u00e9e ?<\/h2>\n\n\n\n<p><strong>L&rsquo;attention divis\u00e9e aussi appel\u00e9e attention partag\u00e9e<\/strong>&nbsp;est le plus haut niveau de la hi\u00e9rarchie \u00e9tablie par le mod\u00e8le clinique de&nbsp;<strong>Sohlberg et Mateer*<\/strong>, suivie de l&rsquo;attention altern\u00e9e, s\u00e9lective, soutenue et focalis\u00e9e. Ce type d&rsquo;attention nous permet&nbsp;<strong>d&rsquo;effectuer plusieurs t\u00e2ches simultan\u00e9ment<\/strong>, ce que l&rsquo;on appelle commun\u00e9ment le&nbsp;<strong>multit\u00e2che<\/strong>. La mise en \u0153uvre de l&rsquo;attention divis\u00e9e commence lorsque nous effectuons deux activit\u00e9s en m\u00eame temps qui n\u00e9cessitent des r\u00e9ponses ou des exigences cognitives diff\u00e9rentes. Mais \u00e9galement lorsque les exigences sont similaires mais que le type de stimulus \u00e0 prendre en compte diff\u00e8re dans chaque activit\u00e9.<\/p>\n\n\n\n<p>Le mod\u00e8le clinique de Sohlberg et Mateer*, expliqu\u00e9 plus en d\u00e9tail dans les articles pr\u00e9c\u00e9dents, \u00e9tablit une&nbsp;<strong>d\u00e9pendance entre les niveaux d&rsquo;attention,<\/strong>&nbsp;de sorte que le bon fonctionnement des niveaux sup\u00e9rieurs d\u00e9pend du fonctionnement des niveaux inf\u00e9rieurs. A propos de l&rsquo;attention altern\u00e9e, la mani\u00e8re dont son fonctionnement d\u00e9pend d&rsquo;une&nbsp;<strong>attention s\u00e9lective, soutenue et focalis\u00e9e<\/strong>&nbsp;a \u00e9t\u00e9 expos\u00e9e. Ainsi, pour \u00e9tablir la subordination du fonctionnement de l&rsquo;attention divis\u00e9e \u00e0 des niveaux inf\u00e9rieurs, il suffit d&rsquo;indiquer la relation \u00e9troite entre ce type d&rsquo;attention et l&rsquo;attention altern\u00e9e \u00e0 travers les mots des auteurs eux-m\u00eames : \u00ab&nbsp;<strong>l&rsquo;attention divis\u00e9e<\/strong>&nbsp;peut refl\u00e9ter une alternance continue d&rsquo;attention et de rapidit\u00e9 ou de confiance \u00bb. sur un traitement automatique plus inconscient pour au moins une des t\u00e2ches.<\/p>\n\n\n\n<p>Cette affirmation indique que, lors de la r\u00e9alisation d&rsquo;une t\u00e2che d&rsquo;attention divis\u00e9e, par exemple envoyer un message avec le mobile pendant que nous marchons dans la rue, nous alternons tr\u00e8s rapidement les deux activit\u00e9s, de sorte que nous pouvons les sortir simultan\u00e9ment. De plus, ils ajoutent que l&rsquo;ex\u00e9cution d&rsquo;une des t\u00e2ches peut \u00eatre&nbsp;<strong>automatique<\/strong>, comme c&rsquo;est le cas de la marche.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"impact-des-stimulis-du-quotidien\">Impact des stimulis du quotidien&nbsp;<\/h3>\n\n\n\n<p>L&rsquo;exemple pr\u00e9c\u00e9dent met en lumi\u00e8re les nombreuses situations quotidiennes dans lesquelles nous activons<strong>&nbsp;l&rsquo;attention divis\u00e9e<\/strong>. Bien que nous ayons toujours \u00e9t\u00e9 expos\u00e9s \u00e0 un grand nombre de stimuli, notamment visuels et auditifs, avec l&rsquo;arriv\u00e9e des appareils mobiles (mobile, tablette, eBook, consoles etc. ), la quantit\u00e9 d&rsquo;informations que nous devons traiter simultan\u00e9ment a augment\u00e9.&nbsp;Ainsi, une t\u00e2che telle que conduire une voiture impliquait d\u00e9j\u00e0 de pr\u00eater attention \u00e0 divers stimuli visuels (les panneaux de signalisation) et auditifs ( le klaxon des autres voitures) tout en ex\u00e9cutant les comportements typiques de la conduite automobile tels qu&rsquo;acc\u00e9l\u00e9rer, freiner etc. Cependant, aujourd&rsquo;hui, il est tr\u00e8s courant de parler au t\u00e9l\u00e9phone en conduisant, de sorte que les demandes cognitives augmentent, n\u00e9cessitant l&rsquo;int\u00e9gration et le bon fonctionnement de l&rsquo;attention \u00e0 tous ses niveaux.<\/p>\n\n\n\n<p>Consid\u00e9rant la grande implication de&nbsp;<strong>l&rsquo;attention divis\u00e9e dans notre vie quotidienne,<\/strong>&nbsp;il n&rsquo;est pas surprenant que les probl\u00e8mes de&nbsp;<strong>multit\u00e2ches<\/strong>, soient ceux qui limitent le plus la r\u00e9int\u00e9gration dans la vie quotidienne. Pour cette raison, il est extr\u00eamement important d&rsquo;inclure ce type de soins dans l&rsquo;\u00e9valuation neuropsychologique apr\u00e8s une l\u00e9sion c\u00e9r\u00e9brale.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<aside class=\"wp-block-group br-1010 has-primary-background-color has-background has-dark-background has-sm-padding-top has-sm-padding-bottom has-sm-padding-left has-sm-padding-right\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center has-white-color has-text-color has-link-color wp-elements-9f6f983844799d08e381206fa0a799e3 is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<p>Obtenez 10 activit\u00e9s gratuites pour travailler l&rsquo;attention soutenue avec vos patients<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\" style=\"--button-secondary-color:var(--color-white);--button-secondary-background:var(--color-custom-1);--button-secondary-background-hover:#cc7e00;\"><a class=\"wp-block-button__link button button-secondary     has-link-color wp-element-button\" href=\"https:\/\/neuronup.com\/redirect\/?target=typeform\/attention10?utm_first_source=Web&#038;utm_first_campaign_name=Worksheets_attention\">Obtenir gratuitement<\/a><\/div>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/aside>\n\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"evaluation-de-l-attention-divisee\">\u00c9valuation de l&rsquo;attention divis\u00e9e<\/h2>\n\n\n\n<p>G\u00e9n\u00e9ralement, lors de l&rsquo;\u00e9valuation de l&rsquo;attention, les tests les plus couramment utilis\u00e9s \u00e9valuent l&rsquo;attention soutenue (le&nbsp;<strong>BTA<\/strong>) et l&rsquo;attention s\u00e9lective (des t\u00e2ches d&rsquo;annulation telles que le&nbsp;<strong>d2<\/strong>). En revanche, dans les batteries rigides telles que les&nbsp;<strong>batteries d&rsquo;intelligence de Wechsler<\/strong>, l&rsquo;attention est \u00e9valu\u00e9e \u00e0 l&rsquo;aide du sous-test des chiffres (attention soutenue), des lettres et des chiffres (attention altern\u00e9e)3. La raret\u00e9 des instruments d&rsquo;\u00e9valuation de l&rsquo;attention divis\u00e9e signifie que, \u00e0 de nombreuses reprises, les probl\u00e8mes dans ce domaine sont rel\u00e9gu\u00e9s au second plan. Une r\u00e9habilitation compl\u00e8te n&rsquo;est donc pas effectu\u00e9e.<\/p>\n\n\n\n<p>On peut penser que des informations sur l&rsquo;attention divis\u00e9e peuvent \u00eatre obtenues en \u00e9valuant les niveaux inf\u00e9rieurs d&rsquo;attention. Cependant, l&rsquo;id\u00e9al est de proc\u00e9der \u00e0 une&nbsp;<strong>\u00e9valuation compl\u00e8te<\/strong>, incluant tous les niveaux, en particulier dans les cas o\u00f9 le probl\u00e8me principal est l&rsquo;attention. \u00c0 cette fin, l&rsquo;instrument d&rsquo;\u00e9valuation de l&rsquo;attention divis\u00e9e le plus largement utilis\u00e9 est le Paced Auditory Serial Addition Test (<strong>PASAT<\/strong>)4.<\/p>\n\n\n\n<p>Dans ce test, le patient est pr\u00e9sent\u00e9, via un CD ou une cassette, avec un chiffre toutes les 3 secondes et sa t\u00e2che est d&rsquo;ajouter chaque nouveau chiffre au pr\u00e9c\u00e9dent, de sorte que, si le premier chiffre est 5 et le second est 2, la bonne r\u00e9ponse est 7, et si le nombre suivant est 8, alors la bonne r\u00e9ponse sera 10 (2+8).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"rehabilitation-de-l-attention\">R\u00e9habilitation de l&rsquo;attention<\/h2>\n\n\n\n<p>Comme pour l&rsquo;\u00e9valuation, on peut aussi conclure qu&rsquo;avec la r\u00e9\u00e9ducation des niveaux inf\u00e9rieurs, on obtient automatiquement une&nbsp;<strong>am\u00e9lioration des niveaux sup\u00e9rieurs<\/strong>, notamment en&nbsp;<strong>attention divis\u00e9e<\/strong>. Cependant, la r\u00e9habilitation des soins doit \u00eatre globale, travailler \u00e0 tous les niveaux de mani\u00e8re hi\u00e9rarchis\u00e9e, afin<\/p>\n\n\n\n<p>que la r\u00e9habilitation ou le renforcement de chaque niveau serve d&rsquo;\u00ab \u00e9chafaudage \u00bb pour l&rsquo;intervention du suivant.<\/p>\n\n\n\n<p>Le programme de r\u00e9habilitation de l&rsquo;attention le plus utilis\u00e9 \u00e0 la fois dans la pratique clinique et dans la recherche est&nbsp;<strong>l&rsquo;Attention Process Training (APT)<\/strong>. &nbsp;L&rsquo;attention soutenue, s\u00e9lective, altern\u00e9e et divis\u00e9e y sont travaill\u00e9es \u00e0 travers des exercices papier-crayon et des t\u00e2ches d&rsquo;\u00e9coute informatis\u00e9es. L&rsquo;entra\u00eenement \u00e0 l&rsquo;attention divis\u00e9e, en particulier, est r\u00e9alis\u00e9 \u00e0 travers&nbsp;<strong>trois modalit\u00e9s<\/strong>&nbsp;de t\u00e2ches* :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lecture compl\u00e8te d&rsquo;un texte et recherche d&rsquo;un stimulus sp\u00e9cifique (par exemple, la lettre h).<\/li>\n\n\n\n<li>Combinaison de t\u00e2ches auditives d&rsquo;attention soutenue avec des t\u00e2ches n\u00e9cessitant une r\u00e9ponse motrice en pr\u00e9sence d&rsquo;un stimulus particulier, \u00e9valuant le temps de r\u00e9action.<\/li>\n\n\n\n<li>Combinaison de t\u00e2ches d&rsquo;attention soutenue avec surveillance du temps (suivi du temps \u00e9coul\u00e9).<\/li>\n<\/ul>\n\n\n\n<p><strong>L&rsquo;APT<\/strong>, comme la plateforme&nbsp;<strong>NeuronUP<\/strong>, dans laquelle de multiples exercices sont disponibles pour travailler sur les diff\u00e9rentes fonctions cognitives, s&rsquo;int\u00e8gre dans les programmes d&rsquo;intervention directement sur les d\u00e9ficits, ce qu&rsquo;on appelle la&nbsp;<strong>restauration fonctionnelle<\/strong>. Cependant, en intervention neuropsychologique, d&rsquo;autres proc\u00e9dures peuvent \u00eatre r\u00e9alis\u00e9es, qui seront appliqu\u00e9es en fonction des caract\u00e9ristiques cliniques et des besoins de chaque patient.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"autres-types-d-interventions\">Autres types d&rsquo;interventions<\/h3>\n\n\n\n<p>De telles proc\u00e9dures ou types d&rsquo;interventions ne sont pas exclusifs, en effet, dans la plupart des cas, ils doivent \u00eatre&nbsp;<strong>combin\u00e9s pour garantir la meilleure r\u00e9cup\u00e9ration du patient.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Compensation\/adaptation fonctionnelle<\/strong>&nbsp;: apr\u00e8s une l\u00e9sion c\u00e9r\u00e9brale, et notamment chez l&rsquo;adulte, il est possible que la fonction endommag\u00e9e ne puisse pas \u00eatre r\u00e9cup\u00e9r\u00e9e, on travaille donc sur d&rsquo;autres fonctions moins alt\u00e9r\u00e9es ou intactes afin qu&rsquo;elles puissent compenser les d\u00e9ficits du patient.<\/li>\n\n\n\n<li><strong>Modifications environnementales :<\/strong>&nbsp;il s&rsquo;agit d&rsquo;adapter l&rsquo;environnement du patient pour favoriser son fonctionnement cognitif. Dans le cas de l&rsquo;attention, une modification de l&rsquo;environnement consisterait \u00e0 r\u00e9duire les distracteurs.<\/li>\n\n\n\n<li><strong>Aides externes :<\/strong>&nbsp;dans le cas o\u00f9 la fonction cognitive ne peut pas \u00eatre r\u00e9cup\u00e9r\u00e9e, le patient re\u00e7oit des mat\u00e9riaux qui lui permettent d&rsquo;effectuer les activit\u00e9s de la vie quotidienne sans d\u00e9pendre de la fonction endommag\u00e9e. Un exemple serait l&rsquo;utilisation d&rsquo;un magn\u00e9tophone en classe pour l&rsquo;\u00e9l\u00e8ve ayant des probl\u00e8mes d&rsquo;attention.<\/li>\n\n\n\n<li><strong>Intervention dans la famille&nbsp;:<\/strong>&nbsp;les probl\u00e8mes cognitifs, comportementaux et \u00e9motionnels des patients atteints de l\u00e9sions c\u00e9r\u00e9brales peuvent \u00eatre une surcharge pour les membres de la famille et\/ou les soignants, il est donc extr\u00eamement important de travailler avec eux par le biais de la psycho\u00e9ducation et du soutien psychologique. En revanche, ils jouent un r\u00f4le actif et essentiel dans la r\u00e9\u00e9ducation, informant des r\u00e9sultats de l&rsquo;intervention en dehors de la consultation ou r\u00e9alisant des activit\u00e9s \u00e0 domicile dans le cadre de la r\u00e9\u00e9ducation.<\/li>\n\n\n\n<li><strong>Interventions comportementales et \u00e9motionnelles :<\/strong>&nbsp;ces probl\u00e8mes peuvent \u00eatre le r\u00e9sultat des alt\u00e9rations organiques caus\u00e9es par la blessure, ou comme une r\u00e9action \u00e9motionnelle aux d\u00e9ficits que le patient remarque.Il est important de ne pas n\u00e9gliger le niveau \u00e9motionnel puisqu&rsquo;il est \u00e9troitement li\u00e9 au fonctionnement cognitif. Par exemple, les sympt\u00f4mes d\u00e9pressifs peuvent aggraver les probl\u00e8mes d&rsquo;attention.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"l-importance-de-la-motivation\">L&rsquo;importance de la motivation<\/h4>\n\n\n\n<p>Au sein de l&rsquo;intervention comportementale et \u00e9motionnelle, le travail sur la motivation m\u00e9rite une attention particuli\u00e8re, puisqu&rsquo;il est un grand alli\u00e9 pour favoriser la r\u00e9habilitation ou la compensation des d\u00e9ficits&nbsp;pour plusieurs raisons :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Am\u00e9liore l&rsquo;adh\u00e9sion \u00e0 l&rsquo;intervention.<\/li>\n\n\n\n<li>Il garantit l&rsquo;effort maximal du patient pour effectuer les t\u00e2ches et obtenir de meilleurs r\u00e9sultats.<\/li>\n\n\n\n<li>Il permet d&rsquo;inclure des t\u00e2ches en dehors de la consultation dans le plan d&rsquo;intervention.<\/li>\n\n\n\n<li>Une fois l&rsquo;intervention termin\u00e9e, elle incite le patient \u00e0 suivre des consignes si besoin.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"pour-augmenter-la-motivation-du-patient-il-est-utile-de-suivre-certaines-directives\">Pour augmenter la motivation du patient, il est utile de suivre certaines directives :<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>D\u00e8s le d\u00e9but, \u00e9tablissez un lien avec le patient, en le mettant \u00e0 l&rsquo;aise dans la consultation et, surtout, en lui donnant la confiance n\u00e9cessaire pour exprimer tous ses doutes et ses \u00e9motions.<\/li>\n\n\n\n<li>Soyez honn\u00eate avec le patient et ne lui donnez pas de faux espoirs.<\/li>\n\n\n\n<li>Adaptez vos attentes \u00e0 ce qui peut \u00eatre r\u00e9alis\u00e9 avec la r\u00e9adaptation.<\/li>\n\n\n\n<li>Au d\u00e9but de l&rsquo;intervention, expliquez en d\u00e9tail en quoi elle consistera, combien de temps elle durera et l&rsquo;engagement qu&rsquo;elle requiert tant de votre part que de la part du th\u00e9rapeute.<\/li>\n\n\n\n<li>\u00c9tablissez des objectifs clairs \u00e0 court et \u00e0 long terme avec le patient, afin qu&rsquo;il puisse \u00e9valuer par lui-m\u00eame les r\u00e9sultats qu&rsquo;il obtient avec l&rsquo;intervention.<\/li>\n\n\n\n<li>Avant chaque s\u00e9ance, expliquez le but des t\u00e2ches \u00e0 r\u00e9aliser, afin que ce qui est r\u00e9alis\u00e9 lors de l&rsquo;intervention ait du sens pour le patient.<\/li>\n\n\n\n<li>Donnez-lui la possibilit\u00e9 de sugg\u00e9rer des id\u00e9es et m\u00eame de prendre de petites d\u00e9cisions, par exemple choisir l&rsquo;ordre des exercices propos\u00e9s pour la s\u00e9ance. De cette fa\u00e7on, vous vous sentirez qu&rsquo;il participe activement \u00e0 la r\u00e9\u00e9ducation.<\/li>\n<\/ul>\n\n\n\n<p>Pour conclure, il convient de mentionner qu&rsquo;apr\u00e8s la mise en \u0153uvre d&rsquo;un programme de r\u00e9adaptation neuropsychologique, il est conseill\u00e9 de surveiller le patient, d&rsquo;\u00e9valuer le fonctionnement cognitif, \u00e9motionnel et comportemental et comment tout cela influence la qualit\u00e9 de vie. Ce dernier aspect est d&rsquo;autant plus pertinent que l&rsquo;atteinte d&rsquo;une meilleure qualit\u00e9 de vie est le but ultime de toute intervention.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group br-0111 has-primary-background-color has-background has-dark-background has-sm-padding-top has-sm-padding-left has-sm-padding-right has-xxl-margin-top\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full desktop-position-absolute desktop-bottom-0 mobile-width-50 mobile-m-inline-auto has-xl-margin-top\"><img decoding=\"async\" width=\"292\" height=\"338\" src=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/10\/certificat-produit.webp\" alt=\"\" class=\"wp-image-31568\" srcset=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/10\/certificat-produit-259x300.webp 259w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/10\/certificat-produit.webp 292w\" sizes=\"(max-width: 292px) 100vw, 292px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-white-color has-text-color\"><strong>Abonnez-vous<\/strong> <br>\u00e0 notre <br>Newsletter<\/h2>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button--1\" style=\"--button-outline-color:var(--color-white);--button-outline-color-hover:rgba(0,0,0,0.8);\"><a class=\"wp-block-button__link button button-outline   wp-element-button\" href=\"https:\/\/neuronup.com\/fr\/newsletter\/\">Abonnez-vous<\/a><\/div>\n\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"les-references\">Les r\u00e9f\u00e9rences<\/h2>\n\n\n\n<ul class=\"wp-block-list has-sm-font-size\">\n<li>Sohlberg MM, Mateer CA. Efficacit\u00e9 du programme d&rsquo;entra\u00eenement de l&rsquo;attention. Journal de neuropsychologie clinique et exp\u00e9rimentale. 1987;9(2):117\u201330.<\/li>\n\n\n\n<li>Sohlberg MM, Mateer CA. Am\u00e9liorer l&rsquo;attention et g\u00e9rer les probl\u00e8mes d&rsquo;attention. Annales de l&rsquo;Acad\u00e9mie des sciences de New York. 2006;931(1):359\u201375.<\/li>\n\n\n\n<li>Amador J.A. \u00c9chelle d&rsquo;intelligence de Wechsler pour adultes-IV (WAIS-IV).2013.<\/li>\n\n\n\n<li>Sherman E.M, Strauss E, Spellacy F. Validit\u00e9 du test d&rsquo;addition en s\u00e9rie auditif rythm\u00e9 (PASAT) chez les adultes r\u00e9f\u00e9r\u00e9s pour une \u00e9valuation neuropsychologique apr\u00e8s un traumatisme cr\u00e2nien. Clin Neuropsych. 1997;11(1):34-45.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Si vous avez aim\u00e9 cet article, vous pourriez \u00e9galement \u00eatre int\u00e9ress\u00e9 par :<\/h3>\n\n\n\n<p><a href=\"https:\/\/neuronup.com\/fr\/nouveautes-neuronup\/reeducation-cognitive-avec-neuronup\/reeducation-de-lattention-alternee\/\">R\u00e9\u00e9ducation de l\u2019attention altern\u00e9e<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/neuronup.com\/fr\/activites-de-neuro-reeducation\/activites-dattention\/lattention-cinq-exercices-pour-le-travailler-et-lameliorer\">L\u2019attention : cinq exercices pour la travailler et l\u2019am\u00e9liorer<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/neuronup.com\/fr\/neuropsychologie-et-informations\/breves-exposition-des-bases-anatomiques-de-lattention\">Br\u00e8ves exposition des bases anatomiques de l\u2019attention<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu&rsquo;est-ce que l&rsquo;attention divis\u00e9e ? L&rsquo;attention divis\u00e9e aussi appel\u00e9e attention partag\u00e9e&nbsp;est le plus haut niveau de la hi\u00e9rarchie \u00e9tablie par le mod\u00e8le clinique de&nbsp;Sohlberg et Mateer*, suivie de l&rsquo;attention altern\u00e9e, s\u00e9lective, soutenue et focalis\u00e9e. Ce type d&rsquo;attention nous permet&nbsp;d&rsquo;effectuer plusieurs t\u00e2ches simultan\u00e9ment, ce que l&rsquo;on appelle commun\u00e9ment le&nbsp;multit\u00e2che. La mise en \u0153uvre de l&rsquo;attention divis\u00e9e &hellip;<\/p>\n","protected":false},"author":192,"featured_media":33602,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[546],"tags":[737,863,799],"class_list":{"2":"type-post","7":"category-activites-dattention","8":"tag-attention","9":"tag-lesions-cerebrales","10":"tag-neuroreeducation","11":"entry"},"acf":[],"_links":{"self":[{"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/posts\/6228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/users\/192"}],"replies":[{"embeddable":true,"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/comments?post=6228"}],"version-history":[{"count":0,"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/posts\/6228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/media\/33602"}],"wp:attachment":[{"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/media?parent=6228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/categories?post=6228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/tags?post=6228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}