{"id":25076,"date":"2025-07-12T09:02:42","date_gmt":"2025-07-12T09:02:42","guid":{"rendered":"https:\/\/neuronup.com\/?p=25076"},"modified":"2025-07-12T09:02:42","modified_gmt":"2025-07-12T09:02:42","slug":"tout-sur-la-memoire","status":"publish","type":"post","link":"https:\/\/neuronup.com\/fr\/neurosciences\/neuropsychologie-et-informations\/memoire\/tout-sur-la-memoire\/","title":{"rendered":"Tout sur la m\u00e9moire"},"content":{"rendered":"\n<p class=\"has-xl-font-size\">Le Docteur en biom\u00e9decine Pablo Barrecheguren nous explique la structure de la m\u00e9moire et nous dit \u00e0 quoi sert chaque type de m\u00e9moire.<\/p>\n\n\n\n<p>Nous avons tendance \u00e0 consid\u00e9rer nos capacit\u00e9s intellectuelles comme des blocs uniques, alors que des comp\u00e9tences telles que <strong>la m\u00e9moire<\/strong> sont plut\u00f4t une <strong>structure compos\u00e9e de diff\u00e9rents<\/strong> <strong>d\u00e9partements<\/strong>. Chacun d\u2019eux est <strong>interconnect\u00e9 mais en m\u00eame temps s\u00e9par\u00e9<\/strong>.<\/p>\n\n\n\n<p>Une preuve en est donn\u00e9e par les maladies qui affectent la m\u00e9moire, comme c\u2019est le cas de la maladie d\u2019Alzheimer  : le Dr Alzheimer lui-m\u00eame avait remarqu\u00e9 que les patients <strong>perdaient certains souvenirs avant d\u2019autres<\/strong>, puisque sa premi\u00e8re patiente diagnostiqu\u00e9e, Auguste Deter, pouvait \u00e9noncer les mois de l\u2019ann\u00e9e sans la moindre erreur, mais \u00e9tait incapable de r\u00e9pondre si on lui demandait quel \u00e9tait le onzi\u00e8me mois de l\u2019ann\u00e9e.<\/p>\n\n\n\n<p>Ou dans le cas d\u2019artistes atteints d\u2019Alzheimer, les patients sont souvent <strong>capables de continuer \u00e0 jouer d\u2019un instrument ou \u00e0 peindre<\/strong>, m\u00eame s\u2019ils ont du mal \u00e0 se souvenir de leur propre nom complet.<\/p>\n\n\n\n<p>Et un autre exemple est le <strong>syndrome de Kleine-Levin<\/strong>, un trouble caract\u00e9ris\u00e9 par des \u00e9pisodes durant lesquels les patients vivent des <strong>modifications de comportement<\/strong>, dorment de 12 \u00e0 21 heures par jour et pr\u00e9sentent des troubles de la m\u00e9moire, pr\u00e9cis\u00e9ment dans la m\u00e9moire de travail (qui est charg\u00e9e de stocker temporairement l\u2019information pendant que nous effectuons une t\u00e2che).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00e9moire \u00e0 long terme<\/h2>\n\n\n\n<p>Mais lorsque nous parlons de m\u00e9moire en g\u00e9n\u00e9ral, nous faisons habituellement r\u00e9f\u00e9rence \u00e0 la m\u00e9moire \u00e0 long terme, celle qui stocke l\u2019information pendant des jours ou m\u00eame des d\u00e9cennies, et qui se divise en deux cat\u00e9gories :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>M\u00e9moire implicite<\/strong>, qui est celle que nous utilisons pour accomplir des actions telles que nouer nos lacets, danser ou faire du v\u00e9lo.<\/li>\n\n\n\n<li><strong>M\u00e9moire d\u00e9clarative<\/strong>, qui englobe toutes nos connaissances conscientes et qui se subdivise \u00e0 son tour en deux sous-sections :\n\n<ol class=\"wp-block-list\">\n<li><strong>La m\u00e9moire s\u00e9mantique<\/strong>, qui regroupe tout ce que nous savons gr\u00e2ce \u00e0 l\u2019\u00e9tude, depuis la voie m\u00e9tabolique du cycle de Krebs, les capitales de l\u2019Europe, jusqu\u2019au fait de savoir que le climat en \u00c9cosse est pluvieux alors que nous n\u2019y avons jamais mis les pieds.<\/li>\n\n\n\n<li><strong>La m\u00e9moire \u00e9pisodique<\/strong> correspond \u00e0 nos souvenirs personnels. Par exemple, si nous savons qu\u2019il pleut en \u00c9cosse parce que nous nous rappelons qu\u2019il pleuvait lors de nos vacances, c\u2019est un souvenir \u00e9pisodique.<\/li>\n<\/ol>\n\n<\/li>\n<\/ol>\n\n\n\n<p>Ces divisions en sous-types de m\u00e9moire ne sont pas arbitraires, car on a observ\u00e9 des diff\u00e9rences fonctionnelles entre elles.<\/p>\n\n\n\n<p>Par exemple, nous savons qu\u2019il est probable que les \u00eatres humains m\u00e9morisent presque toutes leurs exp\u00e9riences tout au long de leur vie (m\u00e9moire \u00e9pisodique). Le probl\u00e8me est que <strong>m\u00e9moriser une information et la rappeler sont deux t\u00e2ches tr\u00e8s diff\u00e9rentes\u2026<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Processus multisyst\u00e9mique<\/h2>\n\n\n\n<p>L\u2019\u00e9tude du cerveau indique que les <strong>lobes temporaux<\/strong> jouent un r\u00f4le crucial dans le stockage des souvenirs, et il est m\u00eame possible de provoquer artificiellement des r\u00e9miniscences : si l\u2019on place des \u00e9lectrodes sur ces zones chez un patient et qu\u2019on les stimule, celui-ci se souvient dans certains cas de m\u00e9moires compl\u00e8tement oubli\u00e9es, au point de parfois vivre des hallucinations compl\u00e8tes o\u00f9 il revit des moments de son pass\u00e9.<\/p>\n\n\n\n<p>Ce ph\u00e9nom\u00e8ne se produit \u00e9galement chez des patients qui d\u00e9veloppent des probl\u00e8mes dans ces r\u00e9gions. Le cas d\u2019une vieille dame irlandaise est document\u00e9 : <strong>elle s\u2019est r\u00e9veill\u00e9e un jour en entendant des chansons de son enfance<\/strong> (des morceaux qu\u2019elle avait oubli\u00e9s depuis des d\u00e9cennies).<\/p>\n\n\n\n<p>La musique a r\u00e9sonn\u00e9 dans sa t\u00eate pendant des mois et ne s\u2019est tue que lorsqu\u2019elle s\u2019est remise d\u2019une petite thrombose touchant son <strong>lobe temporal droit<\/strong>.<\/p>\n\n\n\n<p>Lorsqu\u2019on parle de m\u00e9moire, il faut garder \u00e0 l\u2019esprit qu\u2019il s\u2019agit d\u2019un <strong>processus multisyst\u00e9mique<\/strong> qui implique \u00e9galement des zones du cerveau telles que l\u2019<strong>hippocampe<\/strong> (particuli\u00e8rement important pour la m\u00e9moire spatiale) et les <strong>lobes frontaux<\/strong> (tr\u00e8s impliqu\u00e9s dans la r\u00e9cup\u00e9ration des souvenirs stock\u00e9s).<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group br-0111 has-primary-background-color has-background has-dark-background has-sm-padding-top has-sm-padding-left has-sm-padding-right has-xxl-margin-top\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full desktop-position-absolute desktop-bottom-0 mobile-width-50 mobile-m-inline-auto has-xl-margin-top\"><img decoding=\"async\" width=\"292\" height=\"338\" src=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/10\/certificat-produit.webp\" alt=\"\" class=\"wp-image-31568\" srcset=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/10\/certificat-produit-259x300.webp 259w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/10\/certificat-produit.webp 292w\" sizes=\"(max-width: 292px) 100vw, 292px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-white-color has-text-color\"><strong>Abonnez-vous<\/strong> <br>\u00e0 notre <br>Newsletter<\/h2>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button--1\" style=\"--button-outline-color:var(--color-white);--button-outline-color-hover:rgba(0,0,0,0.8);\"><a class=\"wp-block-button__link button button-outline   wp-element-button\" href=\"https:\/\/neuronup.com\/fr\/newsletter\/\">Abonnez-vous<\/a><\/div>\n\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Un peu d\u2019oubli<\/h2>\n\n\n\n<p>C\u2019est tr\u00e8s int\u00e9ressant de constater qu\u2019au sein du monde de la m\u00e9moire existe l\u2019oppos\u00e9 des maladies neurod\u00e9g\u00e9n\u00e9ratives : l\u2019oubli. Il existe des personnes dot\u00e9es de capacit\u00e9s <strong>mn\u00e9motechniques<\/strong> qui ressemblent carr\u00e9ment \u00e0 des super-h\u00e9ros.<\/p>\n\n\n\n<p>Les cas les plus remarquables, bien que num\u00e9riquement tr\u00e8s rares, sont ceux de personnes qui poss\u00e8dent une \u00ab <strong>m\u00e9moire autobiographique hautement sup\u00e9rieure<\/strong> \u00bb (HSAM, de l\u2019anglais h<em>ighly<\/em> s<em>uperior<\/em> a<em>utobiographical memory<\/em>). Ces personnes sont capables de <strong>se rappeler avec une pr\u00e9cision extr\u00eame presque toute leur vie<\/strong>.<\/p>\n\n\n\n<p>Par exemple, on pourrait leur demander ce qu\u2019ils faisaient il y a vingt ans \u00e0 neuf heures du soir, et ils nous diraient ce qu\u2019ils cuisinaient \u00e0 ce moment-l\u00e0, les v\u00eatements qu\u2019ils portaient, l\u2019odeur qui r\u00e9gnait dans la cuisine et tout ce qu\u2019ils avaient fait au cours de cette journ\u00e9e.<\/p>\n\n\n\n<p>Le probl\u00e8me, c\u2019est que ces personnes sont litt\u00e9ralement <strong>incapables d\u2019oublier<\/strong>, c\u2019est pourquoi on leur recommande, dans la mesure du possible, de mener une vie tranquille, car l\u2019impossibilit\u00e9 d\u2019oublier complique grandement la gu\u00e9rison des traumatismes \u00e9motionnels.<\/p>\n\n\n\n<p>Par exemple, un conseil m\u00e9dical est de ne pas s\u2019engager dans l\u2019arm\u00e9e. Ainsi, de fa\u00e7on ironique, le chemin vers une <strong>m\u00e9moire sans probl\u00e8me passe par un peu d\u2019oubli<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bibliographie<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-sm-font-size\">Aslihan Selimbeyoglu and Josef Parvizi. (2010). <em>Electrical stimulation of the human brain: perceptual and behavioral phenomena reported in the old and new literature<\/em>.<em> Frontiers in Neurology<\/em>. Volume 4, Article 46.<\/li>\n\n\n\n<li class=\"has-sm-font-size\">Draaisma, D. (2012). <em>Alzheimer, supongo<\/em>. Editorial Ariel.<\/li>\n\n\n\n<li class=\"has-sm-font-size\">Joshua Jacobs, Bradley Lega, and Christopher Anderson. (2012). <em>Explaining How Brain Stimulation Can Evoke Memories<\/em>. <em>Journal of Cognitive Neuroscience<\/em>. 24:3, pp. 553\u2013563.<\/li>\n\n\n\n<li class=\"has-sm-font-size\">Miglis, M. G. &amp; Guilleminault, C. (2014). Kleine-Levin syndrome: A review. Nature and Science of Sleep, 6, 19\u201326.<\/li>\n\n\n\n<li class=\"has-sm-font-size\">Nanthia Suthana &amp; Itzhak Fried (2014). <em>Deep Brain Stimulation for Enhancement of Learning and Memory<\/em>. <em>Neuroimage<\/em>, 85(0 3): 996\u20131002<\/li>\n\n\n\n<li class=\"has-sm-font-size\">Richard W. Murrow.<em> (2014). <\/em><em>Penfield\u2019s prediction: a mechanism for deep brain stimulation<\/em>. <em>Frontiers in Neurology<\/em>. Volume 5, Article 213.<\/li>\n\n\n\n<li class=\"has-sm-font-size\">Sacks, O. (2002). Reminiscencias. <em>El hombre que confundi\u00f3 a su mujer con un sombrero<\/em>. Editorial Anagrama.<\/li>\n\n\n\n<li class=\"has-sm-font-size\">Schacter, D. (2001). <em>Los siete pecados de la memoria: c\u00f3mo olvida y recuerda la mente<\/em>. Editorial Ariel.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Si cet article sur la m\u00e9moire vous a plu, il est possible que vous soyez \u00e9galement int\u00e9ress\u00e9 par d\u2019autres de ses articles :<\/h3>\n\n\n<div class=\"mai-grid entries entries-grid has-boxed has-image-full\" style=\"--entry-title-font-size:var(--font-size-lg);--align-text:start;--entry-meta-text-align:start;\"><div class=\"entries-wrap has-columns\" style=\"--columns-xs:1\/1;--columns-sm:1\/1;--columns-md:1\/3;--columns-lg:1\/3;--flex-xs:0 0 var(--flex-basis);--flex-sm:0 0 var(--flex-basis);--flex-md:0 0 var(--flex-basis);--flex-lg:0 0 var(--flex-basis);--column-gap:var(--spacing-lg);--row-gap:var(--spacing-lg);--align-columns:start;\"><article class=\"entry entry-grid is-column has-entry-link has-image has-image-first type-post category-zanzibar tag-enfants tag-projets tag-reeducation-cognitive tag-stimulation-cognitive tag-zanzibar\" style=\"--entry-index:1;\" aria-label=\"Le volontariat chez PsicoNED : Transformer des vies gr\u00e2ce \u00e0 la neuropsychologie\" itemscope itemtype=\"https:\/\/schema.org\/CreativeWork\"><a class=\"entry-image-link\" href=\"https:\/\/neuronup.com\/fr\/projets\/zanzibar\/le-benevolat-chez-psiconed-transformant-des-vies-grace-a-la-neuropsychologie\/\" tabindex=\"-1\" aria-hidden=\"true\"><img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/06\/Voluntariado-PsicoNED-Fundacion-NED-Zanzibar-NeuronUP-1.webp\" class=\"entry-image size-landscape-sm\" alt=\"Groupe de b\u00e9n\u00e9voles dans un espace int\u00e9rieur, mur House of Hope Zanzibar, ambiance chaleureuse et tenue vari\u00e9e.\" srcset=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/06\/Voluntariado-PsicoNED-Fundacion-NED-Zanzibar-NeuronUP-1-300x225.webp 300w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/06\/Voluntariado-PsicoNED-Fundacion-NED-Zanzibar-NeuronUP-1-768x576.webp 768w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/06\/Voluntariado-PsicoNED-Fundacion-NED-Zanzibar-NeuronUP-1-1024x768.webp 1024w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/06\/Voluntariado-PsicoNED-Fundacion-NED-Zanzibar-NeuronUP-1.webp 1200w\" sizes=\"(max-width:599px) 599px, (min-width:600px) and (max-width: 799px) 799px, (min-width:800px) and (max-width: 999px) 333px, (min-width:1000px) 400px\" \/><\/a><div class=\"entry-wrap entry-wrap-grid\"><h3 class=\"entry-title\" itemprop=\"headline\"><a class=\"entry-title-link\" href=\"https:\/\/neuronup.com\/fr\/projets\/zanzibar\/le-benevolat-chez-psiconed-transformant-des-vies-grace-a-la-neuropsychologie\/\" rel=\"bookmark\">Le volontariat chez PsicoNED : Transformer des vies gr\u00e2ce \u00e0 la neuropsychologie<\/a><\/h3>\n<\/div><\/article><article class=\"entry entry-grid is-column has-entry-link has-image has-image-first type-post category-neuropsychologie-et-informations tag-emotions tag-intelligence-emotionnelle tag-neuropsychologie\" style=\"--entry-index:2;\" aria-label=\"La r\u00e9gulation \u00e9motionnelle du point de vue de la neuropsychologie\" itemscope itemtype=\"https:\/\/schema.org\/CreativeWork\"><a class=\"entry-image-link\" href=\"https:\/\/neuronup.com\/fr\/neurosciences\/neuropsychologie-et-informations\/la-regulation-emotionnelle-en-neuropsychologie\/\" tabindex=\"-1\" aria-hidden=\"true\"><img decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/09\/mujer-joven-triste-con-problemas-emocionales.webp\" class=\"entry-image size-landscape-sm\" alt=\"Jeune femme aux cheveux boucl\u00e9s allong\u00e9e sur un lit, recroquevill\u00e9e, tenant un coussin, expression pensive dans un cadre apaisant.\" srcset=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/09\/mujer-joven-triste-con-problemas-emocionales-300x200.webp 300w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/09\/mujer-joven-triste-con-problemas-emocionales-768x512.webp 768w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/09\/mujer-joven-triste-con-problemas-emocionales-1024x683.webp 1024w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/09\/mujer-joven-triste-con-problemas-emocionales.webp 1200w\" sizes=\"(max-width:599px) 599px, (min-width:600px) and (max-width: 799px) 799px, (min-width:800px) and (max-width: 999px) 333px, (min-width:1000px) 400px\" \/><\/a><div class=\"entry-wrap entry-wrap-grid\"><h3 class=\"entry-title\" itemprop=\"headline\"><a class=\"entry-title-link\" href=\"https:\/\/neuronup.com\/fr\/neurosciences\/neuropsychologie-et-informations\/la-regulation-emotionnelle-en-neuropsychologie\/\" rel=\"bookmark\">La r\u00e9gulation \u00e9motionnelle du point de vue de la neuropsychologie<\/a><\/h3>\n<\/div><\/article><article class=\"entry entry-grid is-column has-entry-link has-image has-image-first type-post category-lignes-de-recherche tag-attention\" style=\"--entry-index:3;\" aria-label=\"Impact de l\u2019alimentation riche en OMEGA-3 sur l\u2019attention : Donn\u00e9es scientifiques et applications cliniques\" itemscope itemtype=\"https:\/\/schema.org\/CreativeWork\"><a class=\"entry-image-link\" href=\"https:\/\/neuronup.com\/fr\/investigation\/lignes-de-recherche\/impact-de-lalimentation-riche-en-omega-3-sur-lattention-donnees-scientifiques-et-applications-cliniques\/\" tabindex=\"-1\" aria-hidden=\"true\"><img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2025\/05\/Impact-de-lalimentation-riche-en-OMEGA-3-sur-lattention-Donnees-scientifiques-et-applications-cliniques-400x300.webp\" class=\"entry-image size-landscape-sm\" alt=\"Assortiment d\u2019aliments sains: saumon cru, amandes, noisettes, noix de cajou, avocat et huile d\u2019olive, pr\u00e9sentation naturelle.\" srcset=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2025\/05\/Impact-de-lalimentation-riche-en-OMEGA-3-sur-lattention-Donnees-scientifiques-et-applications-cliniques-400x300.webp 400w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2025\/05\/Impact-de-lalimentation-riche-en-OMEGA-3-sur-lattention-Donnees-scientifiques-et-applications-cliniques-800x600.webp 800w\" sizes=\"(max-width:599px) 599px, (min-width:600px) and (max-width: 799px) 799px, (min-width:800px) and (max-width: 999px) 333px, (min-width:1000px) 400px\" \/><\/a><div class=\"entry-wrap entry-wrap-grid\"><h3 class=\"entry-title\" itemprop=\"headline\"><a class=\"entry-title-link\" href=\"https:\/\/neuronup.com\/fr\/investigation\/lignes-de-recherche\/impact-de-lalimentation-riche-en-omega-3-sur-lattention-donnees-scientifiques-et-applications-cliniques\/\" rel=\"bookmark\">Impact de l\u2019alimentation riche en OMEGA-3 sur l\u2019attention : Donn\u00e9es scientifiques et applications cliniques<\/a><\/h3>\n<\/div><\/article><article class=\"entry entry-grid is-column has-entry-link has-image has-image-first type-post category-troubles-du-langage tag-neuronup tag-troubles-neurodeveloppementaux\" style=\"--entry-index:4;\" aria-label=\"Intervention neuropsychologique avec NeuronUP pour les troubles sp\u00e9cifiques du langage\" itemscope itemtype=\"https:\/\/schema.org\/CreativeWork\"><a class=\"entry-image-link\" href=\"https:\/\/neuronup.com\/fr\/actualites-de-la-stimulation-cognitive\/troubles-du-langage\/intervention-neuropsychologique-avec-neuronup-pour-les-troubles-specifiques-du-langage\/\" tabindex=\"-1\" aria-hidden=\"true\"><img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/11\/image-1200x700-1-1-400x300.webp\" class=\"entry-image size-landscape-sm\" alt=\"Enfant blond assis \u00e0 une table tenant une carte de lettre S; sourire et \u00e9coute par une femme brune dans un cadre \u00e9ducatif.\" srcset=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/11\/image-1200x700-1-1-400x300.webp 400w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/11\/image-1200x700-1-1-800x600.webp 800w\" sizes=\"(max-width:599px) 599px, (min-width:600px) and (max-width: 799px) 799px, (min-width:800px) and (max-width: 999px) 333px, (min-width:1000px) 400px\" \/><\/a><div class=\"entry-wrap entry-wrap-grid\"><h3 class=\"entry-title\" itemprop=\"headline\"><a class=\"entry-title-link\" href=\"https:\/\/neuronup.com\/fr\/actualites-de-la-stimulation-cognitive\/troubles-du-langage\/intervention-neuropsychologique-avec-neuronup-pour-les-troubles-specifiques-du-langage\/\" rel=\"bookmark\">Intervention neuropsychologique avec NeuronUP pour les troubles sp\u00e9cifiques du langage<\/a><\/h3>\n<\/div><\/article><article class=\"entry entry-grid is-column has-entry-link has-image has-image-first type-post category-activites-des-fonctions-executives tag-activites-de-stimulation-cognitive tag-activites-de-stimulation-cognitive-pour-enfants tag-actualites-de-neuronup tag-enfants\" style=\"--entry-index:5;\" aria-label=\"Jeu d&#8217;inhibition pour enfants : Cat\u00e9gories \u00e9clair\" itemscope itemtype=\"https:\/\/schema.org\/CreativeWork\"><a class=\"entry-image-link\" href=\"https:\/\/neuronup.com\/fr\/activites-de-neuro-reeducation\/activites-pour-les-fonctions-cognitives\/activites-des-fonctions-executives\/jeu-dinhibition-pour-enfants-categories-eclair\/\" tabindex=\"-1\" aria-hidden=\"true\"><img decoding=\"async\" width=\"400\" height=\"224\" src=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/05\/Juego-para-ninos-NeuronUP-Categorias-relampago.webp\" class=\"entry-image size-landscape-sm\" alt=\"\u00c9cran NeuronUP pour enfants montrant des mots espagnols par cat\u00e9gorie: animales en haut, perro avec coche verte, ic\u00f4nes \u00e0 gauche.\" srcset=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/05\/Juego-para-ninos-NeuronUP-Categorias-relampago-300x168.webp 300w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/05\/Juego-para-ninos-NeuronUP-Categorias-relampago-768x430.webp 768w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/05\/Juego-para-ninos-NeuronUP-Categorias-relampago-1024x574.webp 1024w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2024\/05\/Juego-para-ninos-NeuronUP-Categorias-relampago.webp 1365w\" sizes=\"(max-width:599px) 599px, (min-width:600px) and (max-width: 799px) 799px, (min-width:800px) and (max-width: 999px) 333px, (min-width:1000px) 400px\" \/><\/a><div class=\"entry-wrap entry-wrap-grid\"><h3 class=\"entry-title\" itemprop=\"headline\"><a class=\"entry-title-link\" href=\"https:\/\/neuronup.com\/fr\/activites-de-neuro-reeducation\/activites-pour-les-fonctions-cognitives\/activites-des-fonctions-executives\/jeu-dinhibition-pour-enfants-categories-eclair\/\" rel=\"bookmark\">Jeu d&#8217;inhibition pour enfants : Cat\u00e9gories \u00e9clair<\/a><\/h3>\n<\/div><\/article><article class=\"entry entry-grid is-column has-entry-link has-image has-image-first type-post category-psychologie tag-fonctions-executives tag-psychologie tag-sante-mentale\" style=\"--entry-index:6;\" aria-label=\"La prise de d\u00e9cision d&rsquo;un point de vue psychologique\" itemscope itemtype=\"https:\/\/schema.org\/CreativeWork\"><a class=\"entry-image-link\" href=\"https:\/\/neuronup.com\/fr\/psychologie\/la-prise-de-decision-dun-point-de-vue-psychologique\/\" tabindex=\"-1\" aria-hidden=\"true\"><img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2025\/04\/La-prise-de-decision-dun-point-de-vue-psychologique-1-400x300.webp\" class=\"entry-image size-landscape-sm\" alt=\"Feuille avec des cases \u00e0 cocher et un marqueur rose, illustrant un processus de v\u00e9rification et de prise de d\u00e9cision.\" srcset=\"https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2025\/04\/La-prise-de-decision-dun-point-de-vue-psychologique-1-300x225.webp 300w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2025\/04\/La-prise-de-decision-dun-point-de-vue-psychologique-1-400x300.webp 400w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2025\/04\/La-prise-de-decision-dun-point-de-vue-psychologique-1-768x576.webp 768w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2025\/04\/La-prise-de-decision-dun-point-de-vue-psychologique-1-800x600.webp 800w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2025\/04\/La-prise-de-decision-dun-point-de-vue-psychologique-1-1024x768.webp 1024w, https:\/\/neuronup.com\/fr\/wp-content\/uploads\/2025\/04\/La-prise-de-decision-dun-point-de-vue-psychologique-1.webp 1200w\" sizes=\"(max-width:599px) 599px, (min-width:600px) and (max-width: 799px) 799px, (min-width:800px) and (max-width: 999px) 333px, (min-width:1000px) 400px\" \/><\/a><div class=\"entry-wrap entry-wrap-grid\"><h3 class=\"entry-title\" itemprop=\"headline\"><a class=\"entry-title-link\" href=\"https:\/\/neuronup.com\/fr\/psychologie\/la-prise-de-decision-dun-point-de-vue-psychologique\/\" rel=\"bookmark\">La prise de d\u00e9cision d&rsquo;un point de vue psychologique<\/a><\/h3>\n<\/div><\/article><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Le Docteur en biom\u00e9decine Pablo Barrecheguren nous explique la structure de la m\u00e9moire et nous dit \u00e0 quoi sert chaque type de m\u00e9moire. Nous avons tendance \u00e0 consid\u00e9rer nos capacit\u00e9s intellectuelles comme des blocs uniques, alors que des comp\u00e9tences telles que la m\u00e9moire sont plut\u00f4t une structure compos\u00e9e de diff\u00e9rents d\u00e9partements. Chacun d\u2019eux est interconnect\u00e9 &hellip;<\/p>\n","protected":false},"author":189,"featured_media":25081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[583],"tags":[724],"class_list":{"2":"type-post","7":"category-memoire","8":"tag-memoire","9":"entry"},"acf":[],"_links":{"self":[{"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/posts\/25076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/users\/189"}],"replies":[{"embeddable":true,"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/comments?post=25076"}],"version-history":[{"count":0,"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/posts\/25076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/media\/25081"}],"wp:attachment":[{"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/media?parent=25076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/categories?post=25076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neuronup.com\/fr\/wp-json\/wp\/v2\/tags?post=25076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}