{"id":32586,"date":"2024-10-31T16:26:00","date_gmt":"2024-10-31T14:26:00","guid":{"rendered":"https:\/\/neuronup.com\/ar\/?page_id=32586"},"modified":"2025-02-21T11:57:28","modified_gmt":"2025-02-21T09:57:28","slug":"%d8%a7%d9%84%d8%b9%d9%85%d9%84%d8%a7%d8%a1","status":"publish","type":"page","link":"https:\/\/neuronup.com\/ar\/%d8%a7%d9%84%d8%b9%d9%85%d9%84%d8%a7%d8%a1\/","title":{"rendered":"\u0627\u0644\u0639\u0645\u0644\u0627\u0621"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/neuronup.com\/wp-content\/uploads\/2022\/v3\/icon-comillas.svg\" alt=\"\" class=\"wp-image-18615\"\/><\/figure>\n\n\n\n<p class=\"has-xxl-margin-bottom\">\u0644\u0642\u062f \u062a\u0645\u0643\u0651\u0646\u0627 \u0645\u0646 \u0627\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0623\u0646 <strong>NeuronUP<\/strong> \u0647\u064a \u0623\u062f\u0627\u0629 <strong>\u0645\u0647\u064a\u0623\u0629 \u0644\u0623\u064a \u0645\u062c\u0627\u0644 \u062a\u062f\u062e\u0644 \u0623\u0648 \u0639\u0645\u0644\u064a\u0629 \u0645\u0639\u0631\u0641\u064a\u0629<\/strong> \u0646\u0631\u063a\u0628 \u0641\u064a \u062a\u062d\u0641\u064a\u0632\u0647\u0627.&#8221;<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<figure class=\"wp-block-image size-full is-style-rounded\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/Vanessa-Guilarte-neuropsychologist.webp\" alt=\"Vanessa Guilarte\" class=\"wp-image-31840\" srcset=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/Vanessa-Guilarte-neuropsychologist-80x80.webp 80w, https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/Vanessa-Guilarte-neuropsychologist-150x150.webp 150w, https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/Vanessa-Guilarte-neuropsychologist-300x300.webp 300w, https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/Vanessa-Guilarte-neuropsychologist-768x768.webp 768w, https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/Vanessa-Guilarte-neuropsychologist.webp 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\">\n<p class=\"has-md-font-size\"><strong>Vanessa Guilarte<\/strong>,<br>\u0623\u062e\u0635\u0627\u0626\u064a\u0629 \u0639\u0644\u0645 \u0627\u0644\u0646\u0641\u0633 \u0627\u0644\u0639\u0635\u0628\u064a<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link button button-link wp-element-button\" href=\"https:\/\/neuronup.com\/ar\/\u0623\u062e\u0628\u0627\u0631-\u0627\u0644\u062a\u062d\u0641\u064a\u0632-\u0627\u0644\u0645\u0639\u0631\u0641\u064a\/\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a-\u0627\u0644\u0646\u0645\u0648-\u0627\u0644\u0639\u0635\u0628\u064a\/\u0627\u0644\u062a\u062d\u0641\u064a\u0632-\u0627\u0644\u0645\u0639\u0631\u0641\u064a-\u0627\u0644\u0647\u062c\u064a\u0646-\u0644\u0645\u062c\u0645\u0648\u0639\u0627\u062a-\u0627\u0644\u0648\u0642\/\">\u0627\u0642\u0631\u0623 \u0627\u0644\u0642\u0635\u0629<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column blog-br-0001 is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"anims-fadein-left alignfull infinite-carousel\">\n<div class='white' style='background:rgba(0,0,0,0); border:solid 0px rgba(0,0,0,0); border-radius:0px; padding:0px 0px 0px 0px; overflow:hidden;'>\n<div id='slider_22380' class='owl-carousel sa_owl_theme autohide-arrows showcase_tablet showcase_mobile' data-slider-id='slider_22380' style='visibility:hidden; width:120%; left:-10%; --widthtab:130%; --lefttab:-15%; --widthmob:140%; --leftmob:-20%;'>\n<div id='slider_22380_slide01' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p><img decoding=\"async\" class=\"alignnone size-full wp-image-1767\" src=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/shiar-sanitas.webp\" alt=\"sanitas\" width=\"260\" height=\"140\" \/><\/p><\/div>\n<div id='slider_22380_slide02' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p><img decoding=\"async\" class=\"alignnone size-full wp-image-1769\" src=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/shiar-sanofi-greyscale.webp\" alt=\"sanofi\" width=\"260\" height=\"140\" \/><\/p><\/div>\n<div id='slider_22380_slide03' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p><img decoding=\"async\" class=\"size-full wp-image-1770\" src=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/shiar-ruber.webp\" alt=\"ruber internacional\" width=\"260\" height=\"140\" \/><\/p><\/div>\n<div id='slider_22380_slide04' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p><img decoding=\"async\" class=\"alignnone size-full wp-image-1771\" src=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/shiar-fremap.webp\" alt=\"fremap\" width=\"260\" height=\"140\" \/><\/p><\/div>\n<div id='slider_22380_slide05' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p><img decoding=\"async\" class=\"alignnone size-full wp-image-1772\" src=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/shiar-red-menni.webp\" alt=\"red menni\" width=\"260\" height=\"140\" \/><\/p><\/div>\n<\/div>\n<div id='showcase_22380' class='showcase_nav owl-nav autohide_arrows'><\/div>\n<\/div>\n<script type='text\/javascript'>\n\tjQuery(document).ready(function() {\n\t\tjQuery('#slider_22380').owlCarousel({\n\t\t\tresponsive:{\n\t\t\t\t0:{ items:3 },\n\t\t\t\t480:{ items:4 },\n\t\t\t\t768:{ items:4 },\n\t\t\t\t980:{ items:5 },\n\t\t\t\t1200:{ items:7 },\n\t\t\t\t1500:{ items:8 }\n\t\t\t},\n\t\t\tautoplay : true,\n\t\t\tautoplayTimeout : 5000,\n\t\t\tautoplayHoverPause : false,\n\t\t\tsmartSpeed : 3000,\n\t\t\tfluidSpeed : 3000,\n\t\t\tautoplaySpeed : 3000,\n\t\t\tnavSpeed : 3000,\n\t\t\tdotsSpeed : 3000,\n\t\t\tloop : true,\n\t\t\tnav : false,\n\t\t\tnavText : ['Previous','Next'],\n\t\t\tnavContainer : '#showcase_22380',\n\t\t\tdots : false,\n\t\t\tresponsiveRefreshRate : 200,\n\t\t\tslideBy : 1,\n\t\t\tmergeFit : true,\n\t\t\tautoHeight : false,\n\t\t\trtl : true,\n\t\t\tmouseDrag : true,\n\t\t\ttouchDrag : true\n\t\t});\n\t\tjQuery('#slider_22380').css('visibility', 'visible');\n\t\tsa_resize_slider_22380();\n\t\twindow.addEventListener('resize', sa_resize_slider_22380);\n\t\tfunction sa_resize_slider_22380() {\n\t\t\tvar min_height = '50';\n\t\t\tvar win_width = jQuery(window).width();\n\t\t\tvar slider_width = jQuery('#slider_22380').width();\n\t\t\tif (win_width < 480) {\n\t\t\t\tvar slide_width = slider_width \/ 3;\n\t\t\t} else if (win_width < 768) {\n\t\t\t\tvar slide_width = slider_width \/ 4;\n\t\t\t} else if (win_width < 980) {\n\t\t\t\tvar slide_width = slider_width \/ 4;\n\t\t\t} else if (win_width < 1200) {\n\t\t\t\tvar slide_width = slider_width \/ 5;\n\t\t\t} else if (win_width < 1500) {\n\t\t\t\tvar slide_width = slider_width \/ 7;\n\t\t\t} else {\n\t\t\t\tvar slide_width = slider_width \/ 8;\n\t\t\t}\n\t\t\tslide_width = Math.round(slide_width);\n\t\t\tvar slide_height = '0';\n\t\t\tif (min_height == 'aspect43') {\n\t\t\t\tslide_height = (slide_width \/ 4) * 3;\t\t\t\tslide_height = Math.round(slide_height);\n\t\t\t} else if (min_height == 'aspect169') {\n\t\t\t\tslide_height = (slide_width \/ 16) * 9;\t\t\t\tslide_height = Math.round(slide_height);\n\t\t\t} else {\n\t\t\t\tslide_height = (slide_width \/ 100) * min_height;\t\t\t\tslide_height = Math.round(slide_height);\n\t\t\t}\n\t\t\tjQuery('#slider_22380 .owl-item .sa_hover_container').css('min-height', slide_height+'px');\n\t\t}\n\t\tset_first_last_active_classes('slider_22380');\n\t\tjQuery('#slider_22380').on('translated.owl.carousel resized.owl.carousel', function(event) {\n\t\t\tset_first_last_active_classes('slider_22380');\n\t\t});\n\t\tfunction set_first_last_active_classes(css_id) {\n\t\t\tvar total = jQuery('#slider_22380 .owl-stage .owl-item.active').length;\n\t\t\tjQuery('#slider_22380 .owl-stage .owl-item').removeClass('sc_partial');\n\t\t\tjQuery('#slider_22380 .owl-stage .owl-item.active').each(function(index){\n\t\t\t\tif (index === 0) {\n\t\t\t\t\tjQuery(this).addClass('sc_partial');\n\t\t\t\t}\n\t\t\t\tif (index === total - 1 && total > 1) {\n\t\t\t\t\tjQuery(this).addClass('sc_partial');\n\t\t\t\t}\n\t\t\t});\n\t\t}\n\t\tvar owl_goto = jQuery('#slider_22380');\n\t\tjQuery('.slider_22380_goto1').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 0);\n\t\t});\n\t\tjQuery('.slider_22380_goto2').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 1);\n\t\t});\n\t\tjQuery('.slider_22380_goto3').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 2);\n\t\t});\n\t\tjQuery('.slider_22380_goto4').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 3);\n\t\t});\n\t\tjQuery('.slider_22380_goto5').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 4);\n\t\t});\n\t\tvar resize_22380 = jQuery('.owl-carousel');\n\t\tresize_22380.on('initialized.owl.carousel', function(e) {\n\t\t\tif (typeof(Event) === 'function') {\n\t\t\t\twindow.dispatchEvent(new Event('resize'));\n\t\t\t} else {\n\t\t\t\tvar evt = window.document.createEvent('UIEvents');\n\t\t\t\tevt.initUIEvent('resize', true, false, window, 0);\n\t\t\t\twindow.dispatchEvent(evt);\n\t\t\t}\n\t\t});\n\t});\n<\/script>\n\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-alt-background-color has-background has-light-background has-md-padding-top has-md-padding-bottom\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns anims-fadein-up is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column ml-2 mr-2 anims-fadein-up is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column ml-2 mr-2 anims-fadein-up is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"28\" height=\"23\" src=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/icon-quotes.svg\" alt=\"\" class=\"wp-image-31749\"><\/figure>\n\n\n\n<p class=\"has-primary-color has-text-color has-md-font-size\">\u0644\u0642\u062f \u0648\u062c\u062f\u0646\u0627 \u0641\u064a <strong>NeuronUP<\/strong> \u0645\u0648\u0631\u062f\u064b\u0627 \u0623\u0633\u0627\u0633\u064a\u064b\u0627 \u064a\u0633\u0627\u0639\u062f\u0646\u0627 \u0639\u0644\u0649 <strong>\u062a\u0648\u0641\u064a\u0631 \u0627\u0644\u0648\u0642\u062a<\/strong> \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0645\u062a\u0644\u0627\u0643 \u0645\u062c\u0645\u0648\u0639\u0629 \u0648\u0627\u0633\u0639\u0629 \u0645\u0646 \u0627\u0644\u0645\u0648\u0627\u0631\u062f \u0648\u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0645\u0632\u064a\u062f \u0645\u0646 \u0641\u0626\u0627\u062a \u0627\u0644\u0645\u0631\u0636\u0649.&#8221;<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image is-style-rounded\">\n<figure class=\"alignleft size-full\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/Laura-Caballero-psychologist.webp\" alt=\"Laura Caballero\" class=\"wp-image-31843\" srcset=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/Laura-Caballero-psychologist-80x80.webp 80w, https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/Laura-Caballero-psychologist-150x150.webp 150w, https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/Laura-Caballero-psychologist-300x300.webp 300w, https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/Laura-Caballero-psychologist-768x768.webp 768w, https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/Laura-Caballero-psychologist.webp 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image is-style-rounded\">\n<figure class=\"alignleft size-full\"><img decoding=\"async\" width=\"241\" height=\"177\" src=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/shiar-afa-alcala.webp\" alt=\"logo afa alcala\" class=\"wp-image-31637\"><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<p class=\"has-md-font-size\"><strong>Laura Caballero<\/strong>,<br>\u0623\u062e\u0635\u0627\u0626\u064a\u0629 \u0639\u0644\u0627\u062c \u0648\u0638\u064a\u0641\u064a<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column ml-2 mr-2 anims-fadein-up is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group anims-fadein-up has-md-content-width\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"28\" height=\"23\" src=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/icon-quotes.svg\" alt=\"\" class=\"wp-image-31749\"\/><\/figure>\n<\/div>\n\n\n<p>\u0646\u062d\u0646 \u0631\u0627\u0636\u0648\u0646 \u062c\u062f\u064b\u0627 \u0639\u0646 NeuronUP \u0641\u064a \u0627\u0644\u062a\u062f\u062e\u0644 \u0627\u0644\u0645\u0639\u0631\u0641\u064a \u0644\u0645\u0631\u0636 \u0627\u0644\u062a\u0635\u0644\u0628 \u0627\u0644\u0645\u062a\u0639\u062f\u062f. \u0643\u0645\u0627 \u0646\u0633\u062a\u062e\u062f\u0645 \u0627\u0644\u0645\u0646\u0635\u0629 \u0623\u064a\u0636\u064b\u0627 \u0641\u064a \u062f\u0627\u0631 \u0627\u0644\u0631\u0639\u0627\u064a\u0629 \u0644\u062f\u064a\u0646\u0627\u060c \u062d\u064a\u062b \u064a\u0643\u0648\u0646 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u0623\u0643\u062b\u0631 \u062a\u0623\u062b\u0631\u064b\u0627 \u062c\u0633\u062f\u064a\u064b\u0627 \u0648\u0645\u0639\u0631\u0641\u064a\u064b\u0627.&#8221;<\/p>\n\n\n<div class=\"mai-columns\"><div class=\"mai-columns-wrap has-columns\" style=\"--column-gap:0px;--row-gap:var(--spacing-xl);--align-columns:start;--align-columns-vertical:center;\">\n<div class=\"mai-column is-column\" style=\"--columns-xs:1\/1;--flex-xs:0 0 var(--flex-basis);--columns-sm:1\/2;--flex-sm:0 0 var(--flex-basis);--columns-md:1\/2;--flex-md:0 0 var(--flex-basis);--columns-lg:1\/2;--flex-lg:0 0 var(--flex-basis);--justify-content:center;\">\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/ADEMBI.webp\" alt=\"ADEMBI\" class=\"wp-image-31638\" srcset=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/ADEMBI-80x80.webp 80w, https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/ADEMBI.webp 150w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>Soraya V\u00e1zquez Caro<\/strong>,<br>\u0623\u062e\u0635\u0627\u0626\u064a\u0629 \u0646\u0641\u0633\u064a\u0629<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"250\" height=\"79\" src=\"https:\/\/neuronup.com\/ar\/wp-content\/uploads\/2024\/10\/shiar-adembi.webp\" alt=\"logo adembi\" class=\"wp-image-31639\" style=\"width:125px;height:40px\"\/><\/figure>\n<\/div>\n<\/div>\n\n<div class=\"mai-column is-column\" style=\"--columns-xs:1\/1;--flex-xs:0 0 var(--flex-basis);--columns-sm:1\/2;--flex-sm:0 0 var(--flex-basis);--columns-md:1\/2;--flex-md:0 0 var(--flex-basis);--columns-lg:1\/2;--flex-lg:0 0 var(--flex-basis);--justify-content:center;\">\n\n<\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column br-0111 p-5 particle-bg anims-fadein-up has-primary-background-color has-background is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-white-color has-text-color\">\u062a\u0639\u0631\u0651\u0641 \u0623\u0643\u062b\u0631 \u0639\u0644\u0649 <br><strong>NeuronUP<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button--1\" style=\"--button-outline-color:var(--color-white);--button-outline-color-hover:rgba(0,0,0,0.8);\"><a class=\"wp-block-button__link button button-outline   wp-element-button\" href=\"https:\/\/neuronup.com\/ar\/%D8%B7%D9%84%D8%A8-%D9%85%D8%B9%D9%84%D9%88%D9%85%D8%A7%D8%AA\/\">\u0627\u0637\u0644\u0628 \u0645\u0639\u0644\u0648\u0645\u0627\u062a<\/a><\/div>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column br-0111 p-5 particle-bg anims-fadein-up has-primary-background-color has-background is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-white-color has-text-color\">\u062c\u0631\u0651\u0628\u0647 \u0645\u062c\u0627\u0646\u0627\u064b<\/h2>\n\n\n\n<p class=\"has-white-color has-text-color\">\u0627\u0644\u0645\u0646\u0635\u0629 \u0627\u0644\u062a\u064a \u064a\u0633\u062a\u062e\u062f\u0645\u0647\u0627 \u0623\u0643\u062b\u0631 \u0645\u0646 <strong>4500 \u0645\u062a\u062e\u0635\u0635<\/strong> \u064a\u0648\u0645\u064a\u0627\u064b<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button orange-button\" style=\"--button-background:var(--color-custom-1);--button-background-hover:#cc7e00;\"><a class=\"wp-block-button__link button   wp-element-button\" href=\"https:\/\/neuronup.com\/ar\/landing-store-user\/\">\u0627\u0637\u0644\u0628 \u0627\u0644\u0646\u0633\u062e\u0629 \u0627\u0644\u062a\u062c\u0631\u064a\u0628\u064a\u0629<img decoding=\"async\" class=\"wp-image-18719\" style=\"width: 8px;\" src=\"\/wp-content\/uploads\/2022\/v3\/icon_rightArrow-white.svg\"><\/a><\/div>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0644\u0642\u062f \u062a\u0645\u0643\u0651\u0646\u0627 \u0645\u0646 \u0627\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0623\u0646 NeuronUP \u0647\u064a \u0623\u062f\u0627\u0629 \u0645\u0647\u064a\u0623\u0629 \u0644\u0623\u064a \u0645\u062c\u0627\u0644 \u062a\u062f\u062e\u0644 \u0623\u0648 \u0639\u0645\u0644\u064a\u0629 \u0645\u0639\u0631\u0641\u064a\u0629 \u0646\u0631\u063a\u0628 \u0641\u064a \u062a\u062d\u0641\u064a\u0632\u0647\u0627.&#8221; Vanessa Guilarte,\u0623\u062e\u0635\u0627\u0626\u064a\u0629 \u0639\u0644\u0645 \u0627\u0644\u0646\u0641\u0633 \u0627\u0644\u0639\u0635\u0628\u064a \u0644\u0642\u062f \u0648\u062c\u062f\u0646\u0627 \u0641\u064a NeuronUP \u0645\u0648\u0631\u062f\u064b\u0627 \u0623\u0633\u0627\u0633\u064a\u064b\u0627 \u064a\u0633\u0627\u0639\u062f\u0646\u0627 \u0639\u0644\u0649 \u062a\u0648\u0641\u064a\u0631 \u0627\u0644\u0648\u0642\u062a \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0645\u062a\u0644\u0627\u0643 \u0645\u062c\u0645\u0648\u0639\u0629 \u0648\u0627\u0633\u0639\u0629 \u0645\u0646 \u0627\u0644\u0645\u0648\u0627\u0631\u062f \u0648\u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0645\u0632\u064a\u062f \u0645\u0646 \u0641\u0626\u0627\u062a \u0627\u0644\u0645\u0631\u0636\u0649.&#8221; Laura Caballero,\u0623\u062e\u0635\u0627\u0626\u064a\u0629 \u0639\u0644\u0627\u062c \u0648\u0638\u064a\u0641\u064a \u0646\u062d\u0646 \u0631\u0627\u0636\u0648\u0646 \u062c\u062f\u064b\u0627 \u0639\u0646 &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"wide-content","footnotes":""},"class_list":{"1":"page","2":"type-page","5":"entry"},"acf":[],"_links":{"self":[{"href":"https:\/\/neuronup.com\/ar\/wp-json\/wp\/v2\/pages\/32586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neuronup.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/neuronup.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/neuronup.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/neuronup.com\/ar\/wp-json\/wp\/v2\/comments?post=32586"}],"version-history":[{"count":0,"href":"https:\/\/neuronup.com\/ar\/wp-json\/wp\/v2\/pages\/32586\/revisions"}],"wp:attachment":[{"href":"https:\/\/neuronup.com\/ar\/wp-json\/wp\/v2\/media?parent=32586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}